﻿{"id":482814,"date":"2023-07-03T16:21:49","date_gmt":"2023-07-03T14:21:49","guid":{"rendered":"https:\/\/burkely.com\/de\/?page_id=482814"},"modified":"2024-03-28T15:28:41","modified_gmt":"2024-03-28T14:28:41","slug":"pflege-reparatur","status":"publish","type":"page","link":"https:\/\/burkely.com\/de\/pflege-reparatur\/","title":{"rendered":"Pflege &amp; Reparatur"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":638,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":302,"editor_notices":[],"footnotes":""},"class_list":["post-482814","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pflege &amp; Reparatur | BURKELY<\/title>\n<meta name=\"description\" content=\"Sehen Sie sich alle BURKELY-Kollektionen auf unserer Website an. Finden Sie die BURKELY Tasche, die Sie suchen und bestellen Sie ganz einfach online! Trendige Taschen, sch\u00f6nste Ledertaschen und Accessoires. \u2714 Kaufen Sie die Kollektion bei BURKELY. \u2714 Sicher einkaufen. \u2714 Bezahlen im Nachhinein m\u00f6glich. \u2714 Hohe Kundenzufriedenheit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/burkely.com\/de\/pflege-reparatur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pflege &amp; Reparatur | BURKELY\" \/>\n<meta property=\"og:description\" content=\"Sehen Sie sich alle BURKELY-Kollektionen auf unserer Website an. Finden Sie die BURKELY Tasche, die Sie suchen und bestellen Sie ganz einfach online! Trendige Taschen, sch\u00f6nste Ledertaschen und Accessoires. \u2714 Kaufen Sie die Kollektion bei BURKELY. \u2714 Sicher einkaufen. \u2714 Bezahlen im Nachhinein m\u00f6glich. \u2714 Hohe Kundenzufriedenheit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/burkely.com\/de\/pflege-reparatur\/\" \/>\n<meta property=\"og:site_name\" content=\"BURKELY\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Burkelybags\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T14:28:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/burkely.com\/de\/wp-content\/uploads\/2021\/11\/BURKELY_weve-got-your-bag_HR-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/pflege-reparatur\\\/\",\"url\":\"https:\\\/\\\/burkely.com\\\/de\\\/pflege-reparatur\\\/\",\"name\":\"Pflege &amp; Reparatur | BURKELY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/#website\"},\"datePublished\":\"2023-07-03T14:21:49+00:00\",\"dateModified\":\"2024-03-28T14:28:41+00:00\",\"description\":\"Sehen Sie sich alle BURKELY-Kollektionen auf unserer Website an. Finden Sie die BURKELY Tasche, die Sie suchen und bestellen Sie ganz einfach online! Trendige Taschen, sch\u00f6nste Ledertaschen und Accessoires. \u2714 Kaufen Sie die Kollektion bei BURKELY. \u2714 Sicher einkaufen. \u2714 Bezahlen im Nachhinein m\u00f6glich. \u2714 Hohe Kundenzufriedenheit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/pflege-reparatur\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/burkely.com\\\/de\\\/pflege-reparatur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/pflege-reparatur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/burkely.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pflege &amp; Reparatur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/burkely.com\\\/de\\\/\",\"name\":\"BURKELY\",\"description\":\"We&#039;ve got your bag!\",\"publisher\":{\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/burkely.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/#organization\",\"name\":\"BURKELY\",\"url\":\"https:\\\/\\\/burkely.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/burkely.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/BURKELY_weve-got-your-bag_HR-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/burkely.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/BURKELY_weve-got-your-bag_HR-scaled.jpg\",\"width\":2560,\"height\":662,\"caption\":\"BURKELY\"},\"image\":{\"@id\":\"https:\\\/\\\/burkely.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Burkelybags\",\"https:\\\/\\\/www.instagram.com\\\/burkely\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10255670\\\/admin\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/burkely0416\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyEFsSrjrobucut0t7BUKEA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pflege &amp; Reparatur | BURKELY","description":"Sehen Sie sich alle BURKELY-Kollektionen auf unserer Website an. Finden Sie die BURKELY Tasche, die Sie suchen und bestellen Sie ganz einfach online! Trendige Taschen, sch\u00f6nste Ledertaschen und Accessoires. \u2714 Kaufen Sie die Kollektion bei BURKELY. \u2714 Sicher einkaufen. \u2714 Bezahlen im Nachhinein m\u00f6glich. \u2714 Hohe Kundenzufriedenheit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/burkely.com\/de\/pflege-reparatur\/","og_locale":"de_DE","og_type":"article","og_title":"Pflege &amp; Reparatur | BURKELY","og_description":"Sehen Sie sich alle BURKELY-Kollektionen auf unserer Website an. Finden Sie die BURKELY Tasche, die Sie suchen und bestellen Sie ganz einfach online! Trendige Taschen, sch\u00f6nste Ledertaschen und Accessoires. \u2714 Kaufen Sie die Kollektion bei BURKELY. \u2714 Sicher einkaufen. \u2714 Bezahlen im Nachhinein m\u00f6glich. \u2714 Hohe Kundenzufriedenheit.","og_url":"https:\/\/burkely.com\/de\/pflege-reparatur\/","og_site_name":"BURKELY","article_publisher":"https:\/\/www.facebook.com\/Burkelybags","article_modified_time":"2024-03-28T14:28:41+00:00","og_image":[{"width":2560,"height":662,"url":"https:\/\/burkely.com\/de\/wp-content\/uploads\/2021\/11\/BURKELY_weve-got-your-bag_HR-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/burkely.com\/de\/pflege-reparatur\/","url":"https:\/\/burkely.com\/de\/pflege-reparatur\/","name":"Pflege &amp; Reparatur | BURKELY","isPartOf":{"@id":"https:\/\/burkely.com\/de\/#website"},"datePublished":"2023-07-03T14:21:49+00:00","dateModified":"2024-03-28T14:28:41+00:00","description":"Sehen Sie sich alle BURKELY-Kollektionen auf unserer Website an. Finden Sie die BURKELY Tasche, die Sie suchen und bestellen Sie ganz einfach online! Trendige Taschen, sch\u00f6nste Ledertaschen und Accessoires. \u2714 Kaufen Sie die Kollektion bei BURKELY. \u2714 Sicher einkaufen. \u2714 Bezahlen im Nachhinein m\u00f6glich. \u2714 Hohe Kundenzufriedenheit.","breadcrumb":{"@id":"https:\/\/burkely.com\/de\/pflege-reparatur\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/burkely.com\/de\/pflege-reparatur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/burkely.com\/de\/pflege-reparatur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/burkely.com\/de\/"},{"@type":"ListItem","position":2,"name":"Pflege &amp; Reparatur"}]},{"@type":"WebSite","@id":"https:\/\/burkely.com\/de\/#website","url":"https:\/\/burkely.com\/de\/","name":"BURKELY","description":"We&#039;ve got your bag!","publisher":{"@id":"https:\/\/burkely.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/burkely.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/burkely.com\/de\/#organization","name":"BURKELY","url":"https:\/\/burkely.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/burkely.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/burkely.com\/de\/wp-content\/uploads\/2021\/11\/BURKELY_weve-got-your-bag_HR-scaled.jpg","contentUrl":"https:\/\/burkely.com\/de\/wp-content\/uploads\/2021\/11\/BURKELY_weve-got-your-bag_HR-scaled.jpg","width":2560,"height":662,"caption":"BURKELY"},"image":{"@id":"https:\/\/burkely.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Burkelybags","https:\/\/www.instagram.com\/burkely\/","https:\/\/www.linkedin.com\/company\/10255670\/admin\/","https:\/\/nl.pinterest.com\/burkely0416\/","https:\/\/www.youtube.com\/channel\/UCyEFsSrjrobucut0t7BUKEA"]}]}},"_links":{"self":[{"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/pages\/482814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/users\/638"}],"replies":[{"embeddable":true,"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/comments?post=482814"}],"version-history":[{"count":5,"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/pages\/482814\/revisions"}],"predecessor-version":[{"id":496638,"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/pages\/482814\/revisions\/496638"}],"wp:attachment":[{"href":"https:\/\/burkely.com\/de\/wp-json\/wp\/v2\/media?parent=482814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}